{"id":9802,"date":"2024-03-01T18:16:00","date_gmt":"2024-03-01T18:16:00","guid":{"rendered":"https:\/\/www.permessonegato.it\/?p=9802"},"modified":"2025-05-18T18:29:54","modified_gmt":"2025-05-18T18:29:54","slug":"catcalling","status":"publish","type":"post","link":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/","title":{"rendered":"Catcalling"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">No estoy en la vitrina<\/h2>\n\n<p class=\"wp-block-paragraph\">El t\u00e9rmino &#8220;<em>catcall<\/em>&#8221; se refer\u00eda originalmente a un dispositivo que emit\u00eda un sonido agudo, parecido a un silbido, utilizado en el siglo XVII para expresar desaprobaci\u00f3n o molestar a los artistas en los teatros. Con el tiempo, el t\u00e9rmino evolucion\u00f3 para describir el acto de silbar o gritar para expresar comentarios no solicitados, especialmente de naturaleza sexual, hacia personas en p\u00fablico. <\/p>\n\n<p class=\"wp-block-paragraph\">Las conductas asociadas con el <em><strong>catcalling<\/strong><\/em> se remontan a normas hist\u00f3ricas en las que los hombres se sent\u00edan con derecho a comentar y controlar la apariencia y el comportamiento de las mujeres.<br\/>En muchas sociedades, los espacios p\u00fablicos estuvieron hist\u00f3ricamente dominados por hombres, y las mujeres en esos espacios a menudo fueron objeto de atenci\u00f3n y comentarios no deseados..<\/p>\n\n<p class=\"wp-block-paragraph\">El <em>catcalling<\/em> se refiere al comportamiento <strong>sexista<\/strong> y <strong>acosador<\/strong> que perpetran algunos hombres hacia mujeres que no conocen y con las que se encuentran en la calle, en el parque o en cualquier lugar de la vida cotidiana.<br\/>Se trata de acoso verbal real que las mujeres sufren en la calle por parte de desconocidos: silbidos, bocinazos, bromas sobre la vestimenta, comentarios sobre la apariencia f\u00edsica, gritos, aplausos o persecuciones a pie o en coche, comentarios sexualmente sugerentes, peticiones o insultos basados \u200b\u200ben la apariencia f\u00edsica de la v\u00edctima.<\/p>\n\n<p class=\"wp-block-paragraph\">En las \u00faltimas d\u00e9cadas<strong> ha aumentado la conciencia y la condena<\/strong> del <em>catcalling<\/em> como una forma de acoso sexual. Movimientos como <em>MeToo<\/em> han generado mayor atenci\u00f3n sobre el tema, promoviendo espacios p\u00fablicos m\u00e1s seguros y desafiando la normalizaci\u00f3n de tales comportamientos.<br\/>Los <em>piropos<\/em> callejeros no s\u00f3lo violan el derecho a la privacidad y la seguridad de la v\u00edctima, sino que tambi\u00e9n contribuyen a perpetuar una cultura de cosificaci\u00f3n sexual y discriminaci\u00f3n de g\u00e9nero.<br\/>Es importante condenar los <em>cat calling<\/em> y promover el <strong>respeto<\/strong> y la <strong>dignidad<\/strong> de todas las personas, independientemente de su g\u00e9ner o. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>No estoy en la vitrina El t\u00e9rmino &#8220;catcall&#8221; se refer\u00eda originalmente a un dispositivo que emit\u00eda un sonido agudo, parecido a un silbido, utilizado en el siglo XVII para expresar desaprobaci\u00f3n o molestar a los artistas en los teatros. Con el tiempo, el t\u00e9rmino evolucion\u00f3 para describir el acto de silbar o gritar para expresar [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":10039,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[57],"class_list":["post-9802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato","tag-glosario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catcalling - PermessoNegato<\/title>\n<meta name=\"description\" content=\"El t\u00e9rmino catcalling se refiere al acoso verbal real que sufren las mujeres en la calle por parte de desconocidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catcalling - PermessoNegato\" \/>\n<meta property=\"og:description\" content=\"El t\u00e9rmino catcalling se refiere al acoso verbal real que sufren las mujeres en la calle por parte de desconocidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/\" \/>\n<meta property=\"og:site_name\" content=\"PermessoNegato\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T18:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-18T18:29:54+00:00\" \/>\n<meta name=\"author\" content=\"giulia.valmacco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"giulia.valmacco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/\"},\"author\":{\"name\":\"giulia.valmacco\",\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/#\\\/schema\\\/person\\\/5c44df68907c0ad24a82225d25d49a56\"},\"headline\":\"Catcalling\",\"datePublished\":\"2024-03-01T18:16:00+00:00\",\"dateModified\":\"2025-05-18T18:29:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/\"},\"wordCount\":336,\"image\":{\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.permessonegato.it\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Catcalling-1080px.jpg\",\"keywords\":[\"Glosario\"],\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/\",\"url\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/\",\"name\":\"Catcalling - PermessoNegato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.permessonegato.it\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Catcalling-1080px.jpg\",\"datePublished\":\"2024-03-01T18:16:00+00:00\",\"dateModified\":\"2025-05-18T18:29:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/#\\\/schema\\\/person\\\/5c44df68907c0ad24a82225d25d49a56\"},\"description\":\"El t\u00e9rmino catcalling se refiere al acoso verbal real que sufren las mujeres en la calle por parte de desconocidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.permessonegato.it\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Catcalling-1080px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.permessonegato.it\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Catcalling-1080px.jpg\",\"width\":1080,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/2024\\\/03\\\/01\\\/catcalling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catcalling\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/\",\"name\":\"PermessoNegato\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/#\\\/schema\\\/person\\\/5c44df68907c0ad24a82225d25d49a56\",\"name\":\"giulia.valmacco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29ac608ff8403d3e0d70b9a6145534b677298977ccb15f16d545d5cbe4c154b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29ac608ff8403d3e0d70b9a6145534b677298977ccb15f16d545d5cbe4c154b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29ac608ff8403d3e0d70b9a6145534b677298977ccb15f16d545d5cbe4c154b4?s=96&d=mm&r=g\",\"caption\":\"giulia.valmacco\"},\"url\":\"https:\\\/\\\/www.permessonegato.it\\\/es\\\/author\\\/giulia-valmacco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catcalling - PermessoNegato","description":"El t\u00e9rmino catcalling se refiere al acoso verbal real que sufren las mujeres en la calle por parte de desconocidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/","og_locale":"es_ES","og_type":"article","og_title":"Catcalling - PermessoNegato","og_description":"El t\u00e9rmino catcalling se refiere al acoso verbal real que sufren las mujeres en la calle por parte de desconocidos.","og_url":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/","og_site_name":"PermessoNegato","article_published_time":"2024-03-01T18:16:00+00:00","article_modified_time":"2025-05-18T18:29:54+00:00","author":"giulia.valmacco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"giulia.valmacco","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/#article","isPartOf":{"@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/"},"author":{"name":"giulia.valmacco","@id":"https:\/\/www.permessonegato.it\/es\/#\/schema\/person\/5c44df68907c0ad24a82225d25d49a56"},"headline":"Catcalling","datePublished":"2024-03-01T18:16:00+00:00","dateModified":"2025-05-18T18:29:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/"},"wordCount":336,"image":{"@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/#primaryimage"},"thumbnailUrl":"https:\/\/www.permessonegato.it\/wp-content\/uploads\/2025\/05\/Catcalling-1080px.jpg","keywords":["Glosario"],"articleSection":["Non categorizzato"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/","url":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/","name":"Catcalling - PermessoNegato","isPartOf":{"@id":"https:\/\/www.permessonegato.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/#primaryimage"},"image":{"@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/#primaryimage"},"thumbnailUrl":"https:\/\/www.permessonegato.it\/wp-content\/uploads\/2025\/05\/Catcalling-1080px.jpg","datePublished":"2024-03-01T18:16:00+00:00","dateModified":"2025-05-18T18:29:54+00:00","author":{"@id":"https:\/\/www.permessonegato.it\/es\/#\/schema\/person\/5c44df68907c0ad24a82225d25d49a56"},"description":"El t\u00e9rmino catcalling se refiere al acoso verbal real que sufren las mujeres en la calle por parte de desconocidos.","breadcrumb":{"@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/#primaryimage","url":"https:\/\/www.permessonegato.it\/wp-content\/uploads\/2025\/05\/Catcalling-1080px.jpg","contentUrl":"https:\/\/www.permessonegato.it\/wp-content\/uploads\/2025\/05\/Catcalling-1080px.jpg","width":1080,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.permessonegato.it\/es\/2024\/03\/01\/catcalling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.permessonegato.it\/es\/"},{"@type":"ListItem","position":2,"name":"Catcalling"}]},{"@type":"WebSite","@id":"https:\/\/www.permessonegato.it\/es\/#website","url":"https:\/\/www.permessonegato.it\/es\/","name":"PermessoNegato","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.permessonegato.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.permessonegato.it\/es\/#\/schema\/person\/5c44df68907c0ad24a82225d25d49a56","name":"giulia.valmacco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/29ac608ff8403d3e0d70b9a6145534b677298977ccb15f16d545d5cbe4c154b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/29ac608ff8403d3e0d70b9a6145534b677298977ccb15f16d545d5cbe4c154b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29ac608ff8403d3e0d70b9a6145534b677298977ccb15f16d545d5cbe4c154b4?s=96&d=mm&r=g","caption":"giulia.valmacco"},"url":"https:\/\/www.permessonegato.it\/es\/author\/giulia-valmacco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/posts\/9802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/comments?post=9802"}],"version-history":[{"count":1,"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/posts\/9802\/revisions"}],"predecessor-version":[{"id":9803,"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/posts\/9802\/revisions\/9803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/media\/10039"}],"wp:attachment":[{"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/media?parent=9802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/categories?post=9802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.permessonegato.it\/es\/wp-json\/wp\/v2\/tags?post=9802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}